{"id":14,"date":"2026-06-24T07:42:01","date_gmt":"2026-06-24T07:42:01","guid":{"rendered":"https:\/\/insigniasymedallascorporativas.com\/?page_id=14"},"modified":"2026-07-05T21:38:12","modified_gmt":"2026-07-05T21:38:12","slug":"contacto","status":"publish","type":"page","link":"https:\/\/insigniasymedallascorporativas.com\/index.php\/contacto\/","title":{"rendered":"Contacto"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Movil<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Correo<br>Whatsapp: +34 666 25 36 52<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><\/summary>\n<div class=\"wp-block-joinchat-button joinchat-button--qr-both is-content-justification-center is-vertical\" style=\"gap:10px\"><figure><figcaption>Escanea el c\u00f3digo<\/figcaption><a class=\"joinchat-button__qr is-layout-flex wp-block-joinchat-button-is-layout-flex\" href=\"#whatsapp\" style=\"border-width:6px;border-radius:30px;border-style:solid;border-color:#25d366\"><\/a><\/figure>\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-color has-background has-border-color wp-element-button\" href=\"\" style=\"border-color:#25d366;border-width:6px;border-radius:30px;color:#fff;background-color:#25d366\">Abrir chat<\/a><\/div>\n<\/div>\n<\/details>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<style id=\"wpforms-css-vars-49-block-e4fd0fe0-ee29-4366-9b98-aab7f69d30c8\">\n\t\t\t\t#wpforms-49.wpforms-block-e4fd0fe0-ee29-4366-9b98-aab7f69d30c8 {\n\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-e4fd0fe0-ee29-4366-9b98-aab7f69d30c8 wpforms-render-modern\" id=\"wpforms-49\"><form id=\"wpforms-form-49\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"49\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/14\" data-token=\"27a2db510406ed5d36da5f5bab702f8f\" data-token-time=\"1784136775\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/div><div class=\"wpforms-field-container\">\t\t<div id=\"wpforms-49-field_4-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"4\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-49-field_4\" >mensaje Correo electr\u00f3nico<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-49-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-49-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Nombre <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-49-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-49-field_1-error\" required><label for=\"wpforms-49-field_1\" class=\"wpforms-field-sublabel after\">Nombre<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-49-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" aria-errormessage=\"wpforms-49-field_1-last-error\" required><label for=\"wpforms-49-field_1-last\" class=\"wpforms-field-sublabel after\">Apellidos<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-49-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-49-field_2\">Correo electr\u00f3nico <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-49-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-49-field_2-error\" required><\/div><div id=\"wpforms-49-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-49-field_3\">Comentario o mensaje<\/label><textarea id=\"wpforms-49-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-49-field_3-error\" ><\/textarea><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-49-field_4-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-49-field_4-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-49-field_4-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"49\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/insigniasymedallascorporativas.com\/index.php\/wp-json\/wp\/v2\/pages\/14\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-49\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/insigniasymedallascorporativas.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Movil CorreoWhatsapp: +34 666 25 36 52<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-14","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/insigniasymedallascorporativas.com\/index.php\/wp-json\/wp\/v2\/pages\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insigniasymedallascorporativas.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/insigniasymedallascorporativas.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/insigniasymedallascorporativas.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/insigniasymedallascorporativas.com\/index.php\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":5,"href":"https:\/\/insigniasymedallascorporativas.com\/index.php\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"predecessor-version":[{"id":55,"href":"https:\/\/insigniasymedallascorporativas.com\/index.php\/wp-json\/wp\/v2\/pages\/14\/revisions\/55"}],"wp:attachment":[{"href":"https:\/\/insigniasymedallascorporativas.com\/index.php\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}